{"id":617,"count":5,"description":"","link":"https:\/\/molenkoning.com\/sv\/ufaq-category\/sweden-fence-pt\/","name":"Sweden Fence PT","slug":"sweden-fence-pt","taxonomy":"ufaq-category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/molenkoning.com\/sv\/wp-json\/wp\/v2\/ufaq-category\/617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/molenkoning.com\/sv\/wp-json\/wp\/v2\/ufaq-category"}],"about":[{"href":"https:\/\/molenkoning.com\/sv\/wp-json\/wp\/v2\/taxonomies\/ufaq-category"}],"wp:post_type":[{"href":"https:\/\/molenkoning.com\/sv\/wp-json\/wp\/v2\/ufaq?ufaq-category=617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}