{"id":27126,"date":"2020-07-02T12:43:27","date_gmt":"2020-07-02T12:43:27","guid":{"rendered":"https:\/\/molenkoning.com\/vais-je-recevoir-le-produit-chez-moi-5\/"},"modified":"2022-02-03T10:50:57","modified_gmt":"2022-02-03T10:50:57","slug":"vais-je-recevoir-le-produit-chez-moi-5","status":"publish","type":"ufaq","link":"https:\/\/molenkoning.com\/es\/ufaqs\/vais-je-recevoir-le-produit-chez-moi-5\/","title":{"rendered":"Vais-je recevoir mon solarium chez moi dans mes \u00e9curies ?"},"content":{"rendered":"<style>.ewd-ufaq-faq-title h4{\r\nfont-size:16px !important;\r\n}\r\ndiv.ewd-ufaq-faq-title div.ewd-ufaq-post-margin-symbol{\r\n    float: right;\r\n    line-height: 33px;\r\n}\r\n.ewd-ufaq-faq-title .ewd-ufaq-post-margin-symbol span{\r\nfont-size: 17px;\r\n}\r\n\r\n.ewd-ufaq-faq-div{\r\nbox-shadow: -1px 2px 8px 4px rgba(0,0,0,0.25);\r\n-webkit-box-shadow: -1px 2px 8px 4px rgba(0,0,0,0.25);\r\n-moz-box-shadow: -1px 2px 8px 4px rgba(0,0,0,0.25);\r\npadding: 10px;\r\nmargin-bottom: 15px;\r\n}<\/style><div  class=\"ewd-ufaq-faq-list ewd-ufaq-page-type-load_more ewd-ufaq-category-tabs-\" id='ewd-ufaq-faq-list'>\n\n\t<input type='hidden' name='show_on_load' value='' id='ewd-ufaq-show-on-load' \/>\n<input type='hidden' name='include_category' value='' id='ewd-ufaq-include-category' \/>\n<input type='hidden' name='exclude_category' value='' id='ewd-ufaq-exclude-category' \/>\n<input type='hidden' name='orderby' value='date' id='ewd-ufaq-orderby' \/>\n<input type='hidden' name='order' value='asc' id='ewd-ufaq-order' \/>\n<input type='hidden' name='post_count' value='-1' id='ewd-ufaq-post-count' \/>\n<input type='hidden' name='current_url' value='\/es\/wp-json\/wp\/v2\/ufaq\/27126' id='ewd-ufaq-current-url' \/>\n\t\n\t\n\t<div class='ewd-ufaq-faqs'>\n\n\t\t<div  class=\"ewd-ufaq-faq-div ewd-ufaq-faq-column-count-one ewd-ufaq-faq-responsive-columns- ewd-ufaq-faq-display-style-default ewd-ufaq-can-be-toggled\" id='ewd-ufaq-post-27126-nuFAaHTXXo' data-post_id='27126'>\n\n\t\t\n\t<div class='ewd-ufaq-faq-title ewd-ufaq-faq-toggle'>\n\t\n\t<a class='ewd-ufaq-post-margin'  href='#' role=\"button\">\n\n\t\t<div class='ewd-ufaq-post-margin-symbol ewd-ufaq-square'>\n\t\t\t<span >A<\/span>\n\t\t<\/div>\n\n\t\t<div class='ewd-ufaq-faq-title-text'>\n\n\t\t\t<h4>\n\t\t\t\tVais-je recevoir mon solarium chez moi dans mes \u00e9curies ?\t\t\t<\/h4>\n\n\t\t<\/div>\n\n\t\t<div class='ewd-ufaq-clear'><\/div>\n\n\t<\/a>\n\t\n<\/div>\n\t\n\t<div class='ewd-ufaq-faq-body' >\n\n\t\t\n\t\t\t\n\t\t\n\t\t\t<div class='ewd-ufaq-post-margin ewd-ufaq-faq-post'>\n\t<p>Comme vous le souhaitez ! Nous pouvons nous charger d\u2019organiser le transport jusqu\u2019\u00e0 votre domicile ou vous \u00eates libre de le r\u00e9cup\u00e9rer \u00e0 notre entrep\u00f4t. Nous envoyons tous les jours des solariums dans le monde entier. Nous pouvons organiser les documents d\u2019exportation pour les clients qui en ont besoin. N\u2019h\u00e9sitez pas \u00e0 nous demander les tarifs pour votre transport.<\/p>\n<\/div>\n\t\t\n\t\t\t<div class='ewd-ufaq-faq-custom-fields'>\n\n\t\n<\/div>\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t<\/div>\n\n<\/div>\n\t<\/div>\n\n\t\n<\/div>","protected":false},"excerpt":{"rendered":"<p>A Vais-je recevoir mon solarium chez moi dans mes \u00e9curies ? Comme vous le souhaitez ! Nous pouvons nous charger d\u2019organiser le transport jusqu\u2019\u00e0 votre domicile ou vous \u00eates libre de le r\u00e9cup\u00e9rer \u00e0 notre entrep\u00f4t. Nous envoyons tous les jours des solariums dans le monde entier. Nous pouvons organiser les documents d\u2019exportation pour les [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","ufaq-category":[360],"ufaq-tag":[],"class_list":["post-27126","ufaq","type-ufaq","status-publish","hentry","ufaq-category-solarium-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/molenkoning.com\/es\/wp-json\/wp\/v2\/ufaq\/27126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/molenkoning.com\/es\/wp-json\/wp\/v2\/ufaq"}],"about":[{"href":"https:\/\/molenkoning.com\/es\/wp-json\/wp\/v2\/types\/ufaq"}],"author":[{"embeddable":true,"href":"https:\/\/molenkoning.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/molenkoning.com\/es\/wp-json\/wp\/v2\/comments?post=27126"}],"wp:attachment":[{"href":"https:\/\/molenkoning.com\/es\/wp-json\/wp\/v2\/media?parent=27126"}],"wp:term":[{"taxonomy":"ufaq-category","embeddable":true,"href":"https:\/\/molenkoning.com\/es\/wp-json\/wp\/v2\/ufaq-category?post=27126"},{"taxonomy":"ufaq-tag","embeddable":true,"href":"https:\/\/molenkoning.com\/es\/wp-json\/wp\/v2\/ufaq-tag?post=27126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}