{"id":176022,"date":"2023-10-03T13:36:43","date_gmt":"2023-10-03T13:36:43","guid":{"rendered":"https:\/\/molenkoning.com\/?post_type=ufaq&#038;p=176022"},"modified":"2023-10-03T13:36:43","modified_gmt":"2023-10-03T13:36:43","slug":"dove-posso-acquistare-pezzi-di-ricambio-per-il-mio-solarium-mk-ad-esempio-lampade-aggiuntive","status":"publish","type":"ufaq","link":"https:\/\/molenkoning.com\/de\/ufaqs\/dove-posso-acquistare-pezzi-di-ricambio-per-il-mio-solarium-mk-ad-esempio-lampade-aggiuntive\/","title":{"rendered":"Dove posso acquistare pezzi di ricambio per il mio solarium MK, ad esempio lampade aggiuntive?"},"content":{"rendered":"<style>.ewd-ufaq-faq-title h4{\r\nfont-size:16px !important;\r\n}\r\ndiv.ewd-ufaq-faq-title div.ewd-ufaq-post-margin-symbol{\r\n    float: right;\r\n    line-height: 33px;\r\n}\r\n.ewd-ufaq-faq-title .ewd-ufaq-post-margin-symbol span{\r\nfont-size: 17px;\r\n}\r\n\r\n.ewd-ufaq-faq-div{\r\nbox-shadow: -1px 2px 8px 4px rgba(0,0,0,0.25);\r\n-webkit-box-shadow: -1px 2px 8px 4px rgba(0,0,0,0.25);\r\n-moz-box-shadow: -1px 2px 8px 4px rgba(0,0,0,0.25);\r\npadding: 10px;\r\nmargin-bottom: 15px;\r\n}<\/style><div  class=\"ewd-ufaq-faq-list ewd-ufaq-page-type-load_more ewd-ufaq-category-tabs-\" id='ewd-ufaq-faq-list'>\n\n\t<input type='hidden' name='show_on_load' value='' id='ewd-ufaq-show-on-load' \/>\n<input type='hidden' name='include_category' value='' id='ewd-ufaq-include-category' \/>\n<input type='hidden' name='exclude_category' value='' id='ewd-ufaq-exclude-category' \/>\n<input type='hidden' name='orderby' value='date' id='ewd-ufaq-orderby' \/>\n<input type='hidden' name='order' value='asc' id='ewd-ufaq-order' \/>\n<input type='hidden' name='post_count' value='-1' id='ewd-ufaq-post-count' \/>\n<input type='hidden' name='current_url' value='\/de\/wp-json\/wp\/v2\/ufaq\/176022' id='ewd-ufaq-current-url' \/>\n\t\n\t\n\t<div class='ewd-ufaq-faqs'>\n\n\t\t<div  class=\"ewd-ufaq-faq-div ewd-ufaq-faq-column-count-one ewd-ufaq-faq-responsive-columns- ewd-ufaq-faq-display-style-default ewd-ufaq-can-be-toggled\" id='ewd-ufaq-post-176022-Erb4yNSVGO' data-post_id='176022'>\n\n\t\t\n\t<div class='ewd-ufaq-faq-title ewd-ufaq-faq-toggle'>\n\t\n\t<a class='ewd-ufaq-post-margin'  href='#' role=\"button\">\n\n\t\t<div class='ewd-ufaq-post-margin-symbol ewd-ufaq-square'>\n\t\t\t<span >A<\/span>\n\t\t<\/div>\n\n\t\t<div class='ewd-ufaq-faq-title-text'>\n\n\t\t\t<h4>\n\t\t\t\tDove posso acquistare pezzi di ricambio per il mio solarium MK, ad esempio lampade aggiuntive?\t\t\t<\/h4>\n\n\t\t<\/div>\n\n\t\t<div class='ewd-ufaq-clear'><\/div>\n\n\t<\/a>\n\t\n<\/div>\n\t\n\t<div class='ewd-ufaq-faq-body' >\n\n\t\t\n\t\t\t\n\t\t\n\t\t\t<div class='ewd-ufaq-post-margin ewd-ufaq-faq-post'>\n\t<p>Abbiamo sempre le lampade in stock.<\/p>\n<\/div>\n\t\t\n\t\t\t<div class='ewd-ufaq-faq-custom-fields'>\n\n\t\n<\/div>\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t\t\t\n\t\t\n\t<\/div>\n\n<\/div>\n\t<\/div>\n\n\t\n<\/div>","protected":false},"excerpt":{"rendered":"<p>A Dove posso acquistare pezzi di ricambio per il mio solarium MK, ad esempio lampade aggiuntive? Abbiamo sempre le lampade in stock.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","ufaq-category":[585],"ufaq-tag":[],"class_list":["post-176022","ufaq","type-ufaq","status-publish","hentry","ufaq-category-solarium-it"],"acf":[],"_links":{"self":[{"href":"https:\/\/molenkoning.com\/de\/wp-json\/wp\/v2\/ufaq\/176022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/molenkoning.com\/de\/wp-json\/wp\/v2\/ufaq"}],"about":[{"href":"https:\/\/molenkoning.com\/de\/wp-json\/wp\/v2\/types\/ufaq"}],"author":[{"embeddable":true,"href":"https:\/\/molenkoning.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/molenkoning.com\/de\/wp-json\/wp\/v2\/comments?post=176022"}],"wp:attachment":[{"href":"https:\/\/molenkoning.com\/de\/wp-json\/wp\/v2\/media?parent=176022"}],"wp:term":[{"taxonomy":"ufaq-category","embeddable":true,"href":"https:\/\/molenkoning.com\/de\/wp-json\/wp\/v2\/ufaq-category?post=176022"},{"taxonomy":"ufaq-tag","embeddable":true,"href":"https:\/\/molenkoning.com\/de\/wp-json\/wp\/v2\/ufaq-tag?post=176022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}